{"id":36,"count":18,"description":"","link":"https:\/\/www.logcabinslv.co.uk\/blog\/log_cabins\/pool-houses\/","name":"Pool Houses","slug":"pool-houses","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.logcabinslv.co.uk\/blog\/wp-json\/wp\/v2\/categories\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.logcabinslv.co.uk\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.logcabinslv.co.uk\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.logcabinslv.co.uk\/blog\/wp-json\/wp\/v2\/posts?categories=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}